{"id":1842,"date":"2025-11-09T17:11:23","date_gmt":"2025-11-09T16:11:23","guid":{"rendered":"https:\/\/www.moticeaimmobiliare.com\/?page_id=1842"},"modified":"2025-12-20T17:03:35","modified_gmt":"2025-12-20T16:03:35","slug":"1842-2","status":"publish","type":"page","link":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/","title":{"rendered":""},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\" style=\"font-size:28px\">RIF.APP.412 ATTICO LUMINOSO \u2013 ULTIMO PIANO<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\" style=\"font-size:28px\"> \u2013 TERRAZZO A TASCA \u2013 BOX AUTO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:28px\">\u2013 MODICA VIA SORDA SAMPIERI N\u00b0116\/E<\/p>\n\n\n\n<p class=\"has-blue-color has-text-color has-link-color has-large-font-size wp-elements-1 wp-block-paragraph\" style=\"letter-spacing:3px\">\u20ac 240.000<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/VISTA_esterna_.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/VISTA_esterna_.jpg\" alt=\"\" class=\"wp-image-1777\" style=\"width:418px;height:auto\"\/><\/a><\/figure>\n<\/div>\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3193.468574217339!2d14.771874541021134!3d36.83125248919281!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x131191d1d22f6415%3A0x2fe4443007119d2f!2sVia%20Sorda%20Sampieri%2C%20116%2FE%2C%2097015%20Modica%20RG!5e0!3m2!1sit!2sit!4v1762628296111!5m2!1sit!2sit\" width=\"550\" height=\"390\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><a href=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/Pianta-Piano-Interrato06112025_01.jpg\"><img decoding=\"async\" src=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/Pianta-Piano-Interrato06112025_01-718x1024.jpg\" alt=\"\" class=\"wp-image-1867\"\/><\/a><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><a href=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/Pianta-Piano-Quinto-Sesto06112025_01.jpg\"><img decoding=\"async\" src=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/Pianta-Piano-Quinto-Sesto06112025_01-718x1024.jpg\" alt=\"\" class=\"wp-image-1868\"\/><\/a><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/Immagine.jpg\" alt=\"\" class=\"wp-image-1881\"\/><\/figure>\n\n\n\n<div class=\"alignnormal\"><!-- MetaSlider 1791 not found --><\/div>\n\n\n<!-- MetaSlider 2491 not found -->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/www.moticeaimmobiliare.com\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-06.33.17_93048866_.jpg\" alt=\"\" class=\"wp-image-892\" style=\"width:545px;height:auto\" srcset=\"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-06.33.17_93048866_.jpg 940w, https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-06.33.17_93048866_-300x251.jpg 300w, https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-06-at-06.33.17_93048866_-768x644.jpg 768w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>DESCRIZIONE<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left has-medium-font-size wp-block-paragraph\">Scopri questo splendido attico di 150 mq situato all&#8217;ultimo piano di una palazzina curata, perfetto per chi cerca un ambiente esclusivo e raffinato. L&#8217;ingresso si apre su una zona giorno open-space, ideale per accogliere gli ospiti e godere di momenti di convivialit\u00e0. La cucina, con accesso diretto al terrazzino, \u00e8 l&#8217;ideale per colazioni all&#8217;aperto o per lavorare in smart-working, avvolti dalla luce naturale che penetra attraverso le ampie finestre.<br><br>La zona notte \u00e8 composta da una camera matrimoniale e una seconda camera da letto, entrambe progettate per garantire il massimo comfort. Completano gli spazi un W. C. e un ripostiglio. Una scala interna conduce al piano superiore, dove si trova una camera matrimoniale con armadiatura su misura, cabina armadio e un bagno finestrato, offrendo un&#8217;ulteriore privacy e funzionalit\u00e0.<br><br>Questo attico \u00e8 stato realizzato con materiali ricercati e presenta parquet ovunque, serramenti nuovi e climatizzazione di ultima generazione per garantire un&#8217;atmosfera calda e contemporanea. Gli spazi sono sfruttati senza sprechi, rendendolo perfetto per una vita moderna. Inoltre, il box auto di 52 mq \u00e8 incluso nel prezzo, offrendo comodit\u00e0 e sicurezza.<br><br>Non perdere l&#8217;occasione di vivere in questo attico unico, dove ogni dettaglio \u00e8 pensato per il tuo benessere. Contattaci per maggiori informazioni o per prenotare una visita!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RIF.APP.412 ATTICO LUMINOSO \u2013 ULTIMO PIANO \u2013 TERRAZZO A TASCA \u2013 BOX AUTO \u2013 MODICA VIA SORDA SAMPIERI N\u00b0116\/E \u20ac 240.000 DESCRIZIONE Scopri questo splendido attico di 150 mq situato all&#8217;ultimo piano di una palazzina curata, perfetto per chi cerca &hellip; <a href=\"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/\">Continua a leggere<span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"onecolumn-page.php","meta":{"footnotes":""},"folder":[46,12],"class_list":["post-1842","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- LA TUA CASA A PORTATA DI MANO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- LA TUA CASA A PORTATA DI MANO\" \/>\n<meta property=\"og:description\" content=\"RIF.APP.412 ATTICO LUMINOSO \u2013 ULTIMO PIANO \u2013 TERRAZZO A TASCA \u2013 BOX AUTO \u2013 MODICA VIA SORDA SAMPIERI N\u00b0116\/E \u20ac 240.000 DESCRIZIONE Scopri questo splendido attico di 150 mq situato all&#8217;ultimo piano di una palazzina curata, perfetto per chi cerca &hellip; Continua a leggere&rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LA TUA CASA A PORTATA DI MANO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Moticea-Immobiliare-100064132535657\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-20T16:03:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/index.php\\\/1842-2\\\/\",\"url\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/index.php\\\/1842-2\\\/\",\"name\":\"- LA TUA CASA A PORTATA DI MANO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/index.php\\\/1842-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/index.php\\\/1842-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/VISTA_esterna_.jpg\",\"datePublished\":\"2025-11-09T16:11:23+00:00\",\"dateModified\":\"2025-12-20T16:03:35+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/index.php\\\/1842-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/index.php\\\/1842-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/VISTA_esterna_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/VISTA_esterna_.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/#website\",\"url\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/\",\"name\":\"moticeaimmobiliare\",\"description\":\"LA NOSTRA AGENZIA\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/#organization\",\"name\":\"moticeaimmobiliare\",\"url\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-cropped-PAGINA-INIZIALE_-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/cropped-cropped-PAGINA-INIZIALE_-1-1.jpg\",\"width\":940,\"height\":300,\"caption\":\"moticeaimmobiliare\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moticeaimmobiliare.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Moticea-Immobiliare-100064132535657\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- LA TUA CASA A PORTATA DI MANO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/","og_locale":"it_IT","og_type":"article","og_title":"- LA TUA CASA A PORTATA DI MANO","og_description":"RIF.APP.412 ATTICO LUMINOSO \u2013 ULTIMO PIANO \u2013 TERRAZZO A TASCA \u2013 BOX AUTO \u2013 MODICA VIA SORDA SAMPIERI N\u00b0116\/E \u20ac 240.000 DESCRIZIONE Scopri questo splendido attico di 150 mq situato all&#8217;ultimo piano di una palazzina curata, perfetto per chi cerca &hellip; Continua a leggere&rarr;","og_url":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/","og_site_name":"LA TUA CASA A PORTATA DI MANO","article_publisher":"https:\/\/www.facebook.com\/p\/Moticea-Immobiliare-100064132535657\/","article_modified_time":"2025-12-20T16:03:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/","url":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/","name":"- LA TUA CASA A PORTATA DI MANO","isPartOf":{"@id":"https:\/\/www.moticeaimmobiliare.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/#primaryimage"},"image":{"@id":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/VISTA_esterna_.jpg","datePublished":"2025-11-09T16:11:23+00:00","dateModified":"2025-12-20T16:03:35+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moticeaimmobiliare.com\/index.php\/1842-2\/#primaryimage","url":"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/VISTA_esterna_.jpg","contentUrl":"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2025\/11\/VISTA_esterna_.jpg"},{"@type":"WebSite","@id":"https:\/\/www.moticeaimmobiliare.com\/#website","url":"https:\/\/www.moticeaimmobiliare.com\/","name":"moticeaimmobiliare","description":"LA NOSTRA AGENZIA","publisher":{"@id":"https:\/\/www.moticeaimmobiliare.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moticeaimmobiliare.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moticeaimmobiliare.com\/#organization","name":"moticeaimmobiliare","url":"https:\/\/www.moticeaimmobiliare.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moticeaimmobiliare.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2024\/06\/cropped-cropped-PAGINA-INIZIALE_-1-1.jpg","contentUrl":"https:\/\/www.moticeaimmobiliare.com\/wp-content\/uploads\/2024\/06\/cropped-cropped-PAGINA-INIZIALE_-1-1.jpg","width":940,"height":300,"caption":"moticeaimmobiliare"},"image":{"@id":"https:\/\/www.moticeaimmobiliare.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Moticea-Immobiliare-100064132535657\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/pages\/1842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/comments?post=1842"}],"version-history":[{"count":32,"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/pages\/1842\/revisions"}],"predecessor-version":[{"id":2503,"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/pages\/1842\/revisions\/2503"}],"wp:attachment":[{"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/media?parent=1842"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.moticeaimmobiliare.com\/index.php\/wp-json\/wp\/v2\/folder?post=1842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}